{"id":40449,"date":"2023-07-05T15:11:01","date_gmt":"2023-07-05T13:11:01","guid":{"rendered":"https:\/\/taha.nl\/vakantiehuizen\/%regio%\/nogal\/"},"modified":"2026-05-13T04:02:34","modified_gmt":"2026-05-13T02:02:34","slug":"nogal","status":"publish","type":"vakantiehuizen","link":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/","title":{"rendered":"Nogal"},"content":{"rendered":"<p>Nogal is one of two independent apartments located on the first floor of a Spanish villa. The apartment is well equipped, with everything you could possibly need for a stress free holiday. Around the villa there are both private and shared terraces, to optimally enjoy the sun and the beautiful views all day long.<\/p>\n<h2>Layout of Nogal<\/h2>\n<p>The accommodation on the first floor of the villa consists of an open plan living\/dining room with a sofa and a fully equipped modern kitchen. A family bathroom with shower and bath services 2 spacious bedrooms (one double and one twin). A private terrace, with dining area under the walnut tree (in spanish Nogal) plus BBQ, offers the option of alfresco dining overlooking the beautiful countryside. The shared swimming pool is located on the lowest terrace where sun loungers and parasols are waiting for you.<\/p>\n<p>This traditional accommodation has a number of low doorways and ceiling jambs which may require you to stoop here and there, please be aware of this. Families with very young children or people with reduced mobility are also warned of the fact that there are many stairs on the site. Bed linen, towels and weekly cleaning are provided, additional cleaning can be arranged upon request at an additional cost.<\/p>\n<h2>Surroundings of the accommodation<\/h2>\n<p>Villanueva de Trabuco is a medium-sized provincial town in the heart of the Andalusia region. From this apartment you can make day trips to Malaga, Cordoba, Granada and Antequera (<a href=\"https:\/\/taha.nl\/en\/blog-en\/el-torcal-de-antequera\/\">El Torcal<\/a>). You are not going to be bored for a day in this area.<\/p>\n<h2>Remarks<\/h2>\n<p>&#8211; Both apartments of the villa are equipped for 4 persons. Going on holiday with 2 families? Also rent <a href=\"\/?regio=estrella\">Estrella<\/a>.<br \/>\n&#8211; On arrival there is a welcome package waiting for you!<\/p>\n","protected":false},"featured_media":40235,"template":"","regio":[382,399,381,417],"class_list":["post-40449","vakantiehuizen","type-vakantiehuizen","status-publish","has-post-thumbnail","hentry","regio-andalusia","regio-antequera-en","regio-spain","regio-villanueva-del-trabuco-en"],"acf":{"tekst_beschikbaarheid":"<ul>\n \t<li>Minimum stay 5 nights.<\/li>\n<\/ul>","tekst_prijs":"Includes\n<ul>\n \t<li>Gas<\/li>\n \t<li>Water<\/li>\n \t<li>Electricity<\/li>\n \t<li>Bath, bed and kitchen linen<\/li>\n \t<li>Cot<\/li>\n \t<li>Final cleaning<\/li>\n<\/ul>","gallerij":[40249,40245,40225,40229,40233,40231,40227,40239,40235,40237,40243,40247],"map":{"lat":37.028732400000003,"lng":-4.2123984999999999,"zoom":13,"markers":[{"label":"Camino de Archidona a Alfarnate, 29313 Villanueva del Trabuco, Andalusia Spain","default_label":"Camino de Archidona a Alfarnate, 29313 Villanueva del Trabuco, Andalusia Spain","lat":37.029991500000001,"lng":-4.3124770999999997,"geocode":[{"name":"Camino de Archidona a Alfarnate, Urbanizaci\u00f3n M\u00aa de los \u00c1ngeles, Villanueva del Trabuco, Nororma, Malaga, Andalusia, 29313, Spain","html":"Camino de Archidona a Alfarnate, 29313 Villanueva del Trabuco, Andalusia Spain","center":{"lat":37.028414300000001,"lng":-4.3131132000000001},"bbox":{"_southWest":{"lat":37.028414300000001,"lng":-4.3131132000000001},"_northEast":{"lat":37.028414300000001,"lng":-4.3131132000000001}},"properties":{"place_id":191166975,"licence":"Data \u00a9 OpenStreetMap contributors, ODbL 1.0. https:\/\/osm.org\/copyright","osm_type":"way","osm_id":346938857,"lat":"37.0284143","lon":"-4.3131132","display_name":"Camino de Archidona a Alfarnate, Urbanizaci\u00f3n M\u00aa de los \u00c1ngeles, Villanueva del Trabuco, Nororma, Malaga, Andalusia, 29313, Spain","address":{"road":"Camino de Archidona a Alfarnate","neighbourhood":"Urbanizaci\u00f3n M\u00aa de los \u00c1ngeles","village":"Villanueva del Trabuco","county":"Nororma","state_district":"Malaga","ISO3166-2-lvl6":"ES-MA","state":"Andalusia","ISO3166-2-lvl4":"ES-AN","postcode":"29313","country":"Spain","country_code":"es","building":"","house_number":"","city":"","town":"","hamlet":""},"boundingbox":["37.02719","37.0351252","-4.3199585","-4.3109188"]}}],"uuid":"marker_64a42c8d9255a"}],"address":"Camino de Archidona a Alfarnate, 29313 Villanueva del Trabuco, Andalusia Spain","layers":["OpenStreetMap.Mapnik"],"version":"1.5.6"},"faciliteiten":[{"item":"Private terrace"},{"item":"TV with Amazon Prime, Netflix and Spanish channels"}],"usps":[{"item":"In the middle of the Kings Cities"},{"item":"Modern decor"},{"item":"Fully equipped"}],"voorzieningen":["bbqcharcoal","cd","dvdplayer","babycot","babychair","fridgefreezer","lounger","microwaveoven","oven","tv","wifi","pool","poolshared"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vakantiehuis Nogal - Andalusia - La Taha<\/title>\n<meta name=\"description\" content=\"Holiday home Nogal is a wonderful place for a family holiday in Andalusia. Take a quick look at the availability -&gt; taha.nl\/en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vakantiehuis Nogal - Andalusia - La Taha\" \/>\n<meta property=\"og:description\" content=\"Holiday home Nogal is a wonderful place for a family holiday in Andalusia. Take a quick look at the availability -&gt; taha.nl\/en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/\" \/>\n<meta property=\"og:site_name\" content=\"La Taha\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lataha\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T02:02:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taha.nl\/wp-content\/uploads\/2023\/06\/Nogal6.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TahaSpanje\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-homes\\\/spain\\\/andalusia\\\/antequera-en\\\/villanueva-del-trabuco-en\\\/nogal\\\/\",\"url\":\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-homes\\\/spain\\\/andalusia\\\/antequera-en\\\/villanueva-del-trabuco-en\\\/nogal\\\/\",\"name\":\"Vakantiehuis Nogal - Andalusia - La Taha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-homes\\\/spain\\\/andalusia\\\/antequera-en\\\/villanueva-del-trabuco-en\\\/nogal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-homes\\\/spain\\\/andalusia\\\/antequera-en\\\/villanueva-del-trabuco-en\\\/nogal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taha.nl\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Nogal6.jpeg\",\"datePublished\":\"2023-07-05T13:11:01+00:00\",\"dateModified\":\"2026-05-13T02:02:34+00:00\",\"description\":\"Holiday home Nogal is a wonderful place for a family holiday in Andalusia. Take a quick look at the availability -> taha.nl\\\/en\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-homes\\\/spain\\\/andalusia\\\/antequera-en\\\/villanueva-del-trabuco-en\\\/nogal\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-homes\\\/spain\\\/andalusia\\\/antequera-en\\\/villanueva-del-trabuco-en\\\/nogal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-homes\\\/spain\\\/andalusia\\\/antequera-en\\\/villanueva-del-trabuco-en\\\/nogal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/taha.nl\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Nogal6.jpeg\",\"contentUrl\":\"https:\\\/\\\/taha.nl\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Nogal6.jpeg\",\"width\":720,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-homes\\\/spain\\\/andalusia\\\/antequera-en\\\/villanueva-del-trabuco-en\\\/nogal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Holiday homes\",\"item\":\"https:\\\/\\\/taha.nl\\\/en\\\/holiday-homes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nogal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/taha.nl\\\/en\\\/\",\"name\":\"La Taha\",\"description\":\"Rent your holiday home in Spain\",\"publisher\":{\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/taha.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/#organization\",\"name\":\"La Taha SC\",\"url\":\"https:\\\/\\\/taha.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/taha.nl\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/taha-logo-klein.png\",\"contentUrl\":\"https:\\\/\\\/taha.nl\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/taha-logo-klein.png\",\"width\":677,\"height\":544,\"caption\":\"La Taha SC\"},\"image\":{\"@id\":\"https:\\\/\\\/taha.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lataha\",\"https:\\\/\\\/x.com\\\/TahaSpanje\",\"https:\\\/\\\/instagram.com\\\/tahaspanje\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/la-taha\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vakantiehuis Nogal - Andalusia - La Taha","description":"Holiday home Nogal is a wonderful place for a family holiday in Andalusia. Take a quick look at the availability -> taha.nl\/en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/","og_locale":"en_US","og_type":"article","og_title":"Vakantiehuis Nogal - Andalusia - La Taha","og_description":"Holiday home Nogal is a wonderful place for a family holiday in Andalusia. Take a quick look at the availability -> taha.nl\/en","og_url":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/","og_site_name":"La Taha","article_publisher":"https:\/\/www.facebook.com\/lataha","article_modified_time":"2026-05-13T02:02:34+00:00","og_image":[{"width":720,"height":1080,"url":"https:\/\/taha.nl\/wp-content\/uploads\/2023\/06\/Nogal6.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TahaSpanje","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/","url":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/","name":"Vakantiehuis Nogal - Andalusia - La Taha","isPartOf":{"@id":"https:\/\/taha.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/#primaryimage"},"image":{"@id":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/#primaryimage"},"thumbnailUrl":"https:\/\/taha.nl\/wp-content\/uploads\/2023\/06\/Nogal6.jpeg","datePublished":"2023-07-05T13:11:01+00:00","dateModified":"2026-05-13T02:02:34+00:00","description":"Holiday home Nogal is a wonderful place for a family holiday in Andalusia. Take a quick look at the availability -> taha.nl\/en","breadcrumb":{"@id":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/#primaryimage","url":"https:\/\/taha.nl\/wp-content\/uploads\/2023\/06\/Nogal6.jpeg","contentUrl":"https:\/\/taha.nl\/wp-content\/uploads\/2023\/06\/Nogal6.jpeg","width":720,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/taha.nl\/en\/holiday-homes\/spain\/andalusia\/antequera-en\/villanueva-del-trabuco-en\/nogal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/taha.nl\/en\/holiday-home\/"},{"@type":"ListItem","position":2,"name":"Holiday homes","item":"https:\/\/taha.nl\/en\/holiday-homes\/"},{"@type":"ListItem","position":3,"name":"Nogal"}]},{"@type":"WebSite","@id":"https:\/\/taha.nl\/en\/#website","url":"https:\/\/taha.nl\/en\/","name":"La Taha","description":"Rent your holiday home in Spain","publisher":{"@id":"https:\/\/taha.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taha.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/taha.nl\/en\/#organization","name":"La Taha SC","url":"https:\/\/taha.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/taha.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/taha.nl\/wp-content\/uploads\/2023\/07\/taha-logo-klein.png","contentUrl":"https:\/\/taha.nl\/wp-content\/uploads\/2023\/07\/taha-logo-klein.png","width":677,"height":544,"caption":"La Taha SC"},"image":{"@id":"https:\/\/taha.nl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lataha","https:\/\/x.com\/TahaSpanje","https:\/\/instagram.com\/tahaspanje","https:\/\/www.linkedin.com\/company\/la-taha"]}]}},"_links":{"self":[{"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/vakantiehuizen\/40449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/vakantiehuizen"}],"about":[{"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/types\/vakantiehuizen"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40247"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40243"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40237"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40235"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40239"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40227"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40231"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40233"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40229"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40225"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40245"},{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media\/40235"}],"wp:attachment":[{"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/media?parent=40449"}],"wp:term":[{"taxonomy":"regio","embeddable":true,"href":"https:\/\/taha.nl\/en\/wp-json\/wp\/v2\/regio?post=40449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}